{"id":14376,"date":"2014-11-19T14:35:45","date_gmt":"2014-11-19T12:35:45","guid":{"rendered":"http:\/\/pr-ide.de\/?p=14376"},"modified":"2016-10-16T15:49:47","modified_gmt":"2016-10-16T14:49:47","slug":"ermland-masuren-unter-segeln","status":"publish","type":"post","link":"https:\/\/pr-ide.de\/en\/blog\/2014\/11\/ermland-masuren-unter-segeln\/","title":{"rendered":"Ermland-Masuren unter Segeln"},"content":{"rendered":"<p>Im November ist eigentlich nicht der richtige Zeitpunkt, um eine Region zu erkunden, die mit \u00fcppigen Naturlandschaften und Seen aufwartet und eigentlich f\u00fcr eine Reise in den Sommermonaten besser geeignet ist: Ermland-Masuren. Aber die Phantasie braucht nicht viel, um sich vorzustellen, warum auf den 400 Quadratkilometern sch\u00f6nster Natur im Sommer t\u00e4glich etwa 40.000 Besucher am und auf dem Wasser weilen.<\/p>\n<p>Das Marschallamt der Wojewodschaft Ermland-Masuren lud vom 11. bis zum 14. November 2014 zu einer Kennenlern-Tour ein, die Einblicke in die wirtschaftlichen Anreize zur Ansiedlung von Firmen gew\u00e4hrte, Gespr\u00e4che mit engagierten Seenotrettern erm\u00f6glichte, Besuche \u00f6kologischer Marinas erm\u00f6glichte und ferner einen Blick \u00fcber die Schultern der Delphia-Bootsbauer erlaubte. Nach diesen paar Tagen ergibt sich dank eines ambitionierten und auf die Interessen ausgerichtetes Besucherprogrammes ein erstes Kaleidoskop einer besuchenswerten Region im Osten Europas.<\/p>\n<p>Wir stellen in den n\u00e4chsten Tagen die Highlights der Reise vor.<\/p>\n<p>Hier schon ein Hinweis auf die Website der <a href=\"www.mazury.travel\">Wojewodschaft Ermland-Masuren.<\/a><\/p>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-overflow:visible;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\">\t\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\t\tvar map_fusion_map_6a985fb54b409;\n\t\t\t\t\t\tvar markers = [];\n\t\t\t\t\t\tvar counter = 0;\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tvar fusionMapNonce = 'a575c93f7f';\n\t\t\t\t\t\t\t\t\t\t\t\tfunction fusion_run_map_fusion_map_6a985fb54b409() {\n\t\t\t\t\t\t\tjQuery ('#fusion_map_6a985fb54b409' ).fusion_maps( {\n\t\t\t\t\t\t\t\taddresses: [{\"address\":\"53.709470, 20.376990\",\"infobox_content\":\"53.709470, 20.376990\",\"marker\":\"https:\\\/\\\/pr-ide.de\\\/wp-content\\\/plugins\\\/fusion-builder\\\/images\\\/avada_map_marker.png\",\"coordinates\":false,\"cache\":true,\"latitude\":\"53.625865\",\"longitude\":\"20.40461860000005\"}],\n\t\t\t\t\t\t\t\tanimations: true,\n\t\t\t\t\t\t\t\tinfobox_background_color: 'rgba(181, 41, 41, 0.8)',\n\t\t\t\t\t\t\t\tinfobox_styling: 'custom',\n\t\t\t\t\t\t\t\tinfobox_text_color: '#fff',\n\t\t\t\t\t\t\t\tmap_style: 'custom',\n\t\t\t\t\t\t\t\tmap_type: 'roadmap',\n\t\t\t\t\t\t\t\tmarker_icon: 'theme',\n\t\t\t\t\t\t\t\toverlay_color: '',\n\t\t\t\t\t\t\t\toverlay_color_hsl: {\"hue\":0,\"sat\":63,\"lum\":44},\n\t\t\t\t\t\t\t\tshow_address: true,\n\t\t\t\t\t\t\t\tscale_control: true,\n\t\t\t\t\t\t\t\tscrollwheel: true,\n\t\t\t\t\t\t\t\tzoom: 12,\n\t\t\t\t\t\t\t\tzoom_control: true,\n\t\t\t\t\t\t\t} );\n\t\t\t\t\t\t}\n\n\t\t\t\t\t\tgoogle.maps.event.addDomListener(window, 'load', fusion_run_map_fusion_map_6a985fb54b409);\n\t\t\t\t\t<\/script>\n\t\t\t\t\t<div class=\"shortcode-map fusion-google-map fusion-maps-js-type\" id=\"fusion_map_6a985fb54b409\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im November ist eigentlich nicht der richtige Zeitpunkt, um eine Region zu erkunden, die mit \u00fcppigen Naturlandschaften und Seen aufwartet und eigentlich f\u00fcr eine Reise in den Sommermonaten besser geeignet ist: Ermland-Masuren. Aber die Phantasie braucht nicht viel, um sich  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":14379,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[950,100,564,118,523],"tags":[1066,1336],"class_list":["post-14376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marina","category-pr-ide","category-public-relations","category-tourism","category-tourismus-pr","tag-masuren","tag-pressereise"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ermland-Masuren unter Segeln - pr-ide<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ermland-Masuren unter Segeln - pr-ide\" \/>\n<meta property=\"og:description\" content=\"Im November ist eigentlich nicht der richtige Zeitpunkt, um eine Region zu erkunden, die mit \u00fcppigen Naturlandschaften und Seen aufwartet und eigentlich f\u00fcr eine Reise in den Sommermonaten besser geeignet ist: Ermland-Masuren. Aber die Phantasie braucht nicht viel, um sich [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/\" \/>\n<meta property=\"og:site_name\" content=\"pr-ide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prideberlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-19T12:35:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-16T14:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pr-ide.de\/wp-content\/uploads\/2014\/11\/xx_am-see-Marinagolf-hotel-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martina M\u00fcller\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina M\u00fcller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/\"},\"author\":{\"name\":\"Martina M\u00fcller\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#\\\/schema\\\/person\\\/7cff3097f838f10886a8ddb4a1dfedce\"},\"headline\":\"Ermland-Masuren unter Segeln\",\"datePublished\":\"2014-11-19T12:35:45+00:00\",\"dateModified\":\"2016-10-16T14:49:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/\"},\"wordCount\":270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pr-ide.de\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/xx_am-see-Marinagolf-hotel-scaled.jpg\",\"keywords\":[\"Masuren\",\"Pressereise\"],\"articleSection\":[\"marina\",\"pr-ide\",\"public relations\",\"tourism\",\"tourismus-pr\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/\",\"url\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/\",\"name\":\"Ermland-Masuren unter Segeln - pr-ide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pr-ide.de\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/xx_am-see-Marinagolf-hotel-scaled.jpg\",\"datePublished\":\"2014-11-19T12:35:45+00:00\",\"dateModified\":\"2016-10-16T14:49:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pr-ide.de\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/xx_am-see-Marinagolf-hotel-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/pr-ide.de\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/xx_am-see-Marinagolf-hotel-scaled.jpg\",\"width\":2560,\"height\":1493,\"caption\":\"Blick auf SEe vom Marina Golf Hotel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/blog\\\/2014\\\/11\\\/ermland-masuren-unter-segeln\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pr-ide.de\\\/en\\\/the-agency-for-creative-success\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ermland-Masuren unter Segeln\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#website\",\"url\":\"https:\\\/\\\/pr-ide.de\\\/\",\"name\":\"pr-ide\",\"description\":\"die agentur f\u00fcr kreative erfolge\",\"publisher\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pr-ide.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#organization\",\"name\":\"pr-ide\",\"url\":\"https:\\\/\\\/pr-ide.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"pr-ide\"},\"image\":{\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prideberlin\\\/\",\"https:\\\/\\\/x.com\\\/pr_ide\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pr-ide-gbr\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pr-ide.de\\\/#\\\/schema\\\/person\\\/7cff3097f838f10886a8ddb4a1dfedce\",\"name\":\"Martina M\u00fcller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/561aa09b9e87187e01da837e323f730f46e80fa427035fd00502b3dc65ba1dfd?s=96&d=robohash&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/561aa09b9e87187e01da837e323f730f46e80fa427035fd00502b3dc65ba1dfd?s=96&d=robohash&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/561aa09b9e87187e01da837e323f730f46e80fa427035fd00502b3dc65ba1dfd?s=96&d=robohash&r=g\",\"caption\":\"Martina M\u00fcller\"},\"description\":\"Martina M\u00fcller; PR Referentin, Berlin Seit 2001 Inhaberin von pr-ide pr &amp; industrial design, studierte Italienisch und Russisch und ist als PR-Referentin zertifiziert. Ihr Schwerpunkt bei pr-ide: Public Relations (klassische Medienarbeit und Aufbau einer Online-Reputation). Ihr Know How steht f\u00fcr kreative Konzepte und professionelle Umsetzung. IhreSt\u00e4rken sind ein ausgepr\u00e4gtes Organisationstalent und eine hohe Effektivit\u00e4t. Sie h\u00e4lt Vortr\u00e4ge und f\u00fchrt Seminar und Workshops zum Thema Online-Marketing durch.\",\"url\":\"https:\\\/\\\/pr-ide.de\\\/en\\\/blog\\\/author\\\/mmueller-2-2-2-2-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ermland-Masuren unter Segeln - pr-ide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/","og_locale":"en_US","og_type":"article","og_title":"Ermland-Masuren unter Segeln - pr-ide","og_description":"Im November ist eigentlich nicht der richtige Zeitpunkt, um eine Region zu erkunden, die mit \u00fcppigen Naturlandschaften und Seen aufwartet und eigentlich f\u00fcr eine Reise in den Sommermonaten besser geeignet ist: Ermland-Masuren. Aber die Phantasie braucht nicht viel, um sich [...]","og_url":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/","og_site_name":"pr-ide","article_publisher":"https:\/\/www.facebook.com\/prideberlin\/","article_published_time":"2014-11-19T12:35:45+00:00","article_modified_time":"2016-10-16T14:49:47+00:00","og_image":[{"width":2560,"height":1493,"url":"https:\/\/pr-ide.de\/wp-content\/uploads\/2014\/11\/xx_am-see-Marinagolf-hotel-scaled.jpg","type":"image\/jpeg"}],"author":"Martina M\u00fcller","twitter_misc":{"Written by":"Martina M\u00fcller","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#article","isPartOf":{"@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/"},"author":{"name":"Martina M\u00fcller","@id":"https:\/\/pr-ide.de\/#\/schema\/person\/7cff3097f838f10886a8ddb4a1dfedce"},"headline":"Ermland-Masuren unter Segeln","datePublished":"2014-11-19T12:35:45+00:00","dateModified":"2016-10-16T14:49:47+00:00","mainEntityOfPage":{"@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/"},"wordCount":270,"commentCount":0,"publisher":{"@id":"https:\/\/pr-ide.de\/#organization"},"image":{"@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#primaryimage"},"thumbnailUrl":"https:\/\/pr-ide.de\/wp-content\/uploads\/2014\/11\/xx_am-see-Marinagolf-hotel-scaled.jpg","keywords":["Masuren","Pressereise"],"articleSection":["marina","pr-ide","public relations","tourism","tourismus-pr"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/","url":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/","name":"Ermland-Masuren unter Segeln - pr-ide","isPartOf":{"@id":"https:\/\/pr-ide.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#primaryimage"},"image":{"@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#primaryimage"},"thumbnailUrl":"https:\/\/pr-ide.de\/wp-content\/uploads\/2014\/11\/xx_am-see-Marinagolf-hotel-scaled.jpg","datePublished":"2014-11-19T12:35:45+00:00","dateModified":"2016-10-16T14:49:47+00:00","breadcrumb":{"@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#primaryimage","url":"https:\/\/pr-ide.de\/wp-content\/uploads\/2014\/11\/xx_am-see-Marinagolf-hotel-scaled.jpg","contentUrl":"https:\/\/pr-ide.de\/wp-content\/uploads\/2014\/11\/xx_am-see-Marinagolf-hotel-scaled.jpg","width":2560,"height":1493,"caption":"Blick auf SEe vom Marina Golf Hotel"},{"@type":"BreadcrumbList","@id":"https:\/\/pr-ide.de\/blog\/2014\/11\/ermland-masuren-unter-segeln\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pr-ide.de\/en\/the-agency-for-creative-success\/"},{"@type":"ListItem","position":2,"name":"Ermland-Masuren unter Segeln"}]},{"@type":"WebSite","@id":"https:\/\/pr-ide.de\/#website","url":"https:\/\/pr-ide.de\/","name":"pr-ide","description":"die agentur f\u00fcr kreative erfolge","publisher":{"@id":"https:\/\/pr-ide.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pr-ide.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pr-ide.de\/#organization","name":"pr-ide","url":"https:\/\/pr-ide.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pr-ide.de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"pr-ide"},"image":{"@id":"https:\/\/pr-ide.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prideberlin\/","https:\/\/x.com\/pr_ide","https:\/\/www.linkedin.com\/company\/pr-ide-gbr\/"]},{"@type":"Person","@id":"https:\/\/pr-ide.de\/#\/schema\/person\/7cff3097f838f10886a8ddb4a1dfedce","name":"Martina M\u00fcller","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/561aa09b9e87187e01da837e323f730f46e80fa427035fd00502b3dc65ba1dfd?s=96&d=robohash&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/561aa09b9e87187e01da837e323f730f46e80fa427035fd00502b3dc65ba1dfd?s=96&d=robohash&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/561aa09b9e87187e01da837e323f730f46e80fa427035fd00502b3dc65ba1dfd?s=96&d=robohash&r=g","caption":"Martina M\u00fcller"},"description":"Martina M\u00fcller; PR Referentin, Berlin Seit 2001 Inhaberin von pr-ide pr &amp; industrial design, studierte Italienisch und Russisch und ist als PR-Referentin zertifiziert. Ihr Schwerpunkt bei pr-ide: Public Relations (klassische Medienarbeit und Aufbau einer Online-Reputation). Ihr Know How steht f\u00fcr kreative Konzepte und professionelle Umsetzung. IhreSt\u00e4rken sind ein ausgepr\u00e4gtes Organisationstalent und eine hohe Effektivit\u00e4t. Sie h\u00e4lt Vortr\u00e4ge und f\u00fchrt Seminar und Workshops zum Thema Online-Marketing durch.","url":"https:\/\/pr-ide.de\/en\/blog\/author\/mmueller-2-2-2-2-2\/"}]}},"jetpack_featured_media_url":"https:\/\/pr-ide.de\/wp-content\/uploads\/2014\/11\/xx_am-see-Marinagolf-hotel-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/posts\/14376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/comments?post=14376"}],"version-history":[{"count":0,"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/posts\/14376\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/media\/14379"}],"wp:attachment":[{"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/media?parent=14376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/categories?post=14376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pr-ide.de\/en\/wp-json\/wp\/v2\/tags?post=14376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}